{"id":12,"date":"2018-04-27T13:13:58","date_gmt":"2018-04-27T09:13:58","guid":{"rendered":"http:\/\/52.213.8.144\/2018\/04\/27\/zotcar-fete-ses-deux-ans\/"},"modified":"2023-07-19T09:11:34","modified_gmt":"2023-07-19T05:11:34","slug":"zotcar-fete-ses-deux-ans","status":"publish","type":"post","link":"https:\/\/www.zotcar.com\/blog\/zotcar-fete-ses-deux-ans\/","title":{"rendered":"ZOTCAR f\u00eate ses deux ans !"},"content":{"rendered":"<p>A cette occasion, nous avons d\u00e9cid\u00e9 d\u2019offrir 100 \u20ac\u00a0 \u00e0 tous les propri\u00e9taires qui inscrivent une nouvelle voiture d\u00e8s aujourd\u2019hui. Ces 100 \u20ac vous seront revers\u00e9s 3 jours apr\u00e8s la fin de votre premi\u00e8re location.<\/p>\n<p>Attention : cette offre se termine le 31 mai 2018 \u00e0 12h00.<\/p>\n<p><!-- more --><\/p>\n<h2>Comment faire ?<\/h2>\n<p>Pour cela, rendez-vous sur zotcar.com et cliquez sur inscrire ma voiture.<\/p>\n<p>Si vous n\u2019\u00eates pas encore inscrit, il faudra cr\u00e9er votre compte.<\/p>\n<p>Ensuite lors de l\u2019\u00e9tape suivante, inscrivez votre voiture et tout en bas de saisissez le code ZOTKDO.<\/p>\n<p>Vous recevrez ensuite 100 \u20ac d\u00e8s que votre premi\u00e8re location a \u00e9t\u00e9 effectu\u00e9e ;).<\/p>\n<p>En esp\u00e9rant que cela vous fasse plaisir, car c\u2019est gr\u00e2ce \u00e0 vous que nous avan\u00e7ons chaque jour\u00a0 ! MERCI ENCORE !<\/p>\n<p>L\u2019\u00e9quipe ZOTCAR<\/p>\n<p><a href=\"https:\/\/www.zotcar.com\/louer-ma-voiture\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-medium wp-image-209 aligncenter\" src=\"http:\/\/zc-blog.s3.eu-west-1.amazonaws.com\/blog\/wp-content\/uploads\/2018\/07\/08103843\/Jinscris-ma-voiture-%C3%A0-Zotcar-300x81.png\" alt=\"\" width=\"300\" height=\"81\" srcset=\"https:\/\/zc-blog.s3.eu-west-1.amazonaws.com\/blog\/wp-content\/uploads\/2018\/07\/08103843\/Jinscris-ma-voiture-%C3%A0-Zotcar-300x81.png 300w, https:\/\/zc-blog.s3.eu-west-1.amazonaws.com\/blog\/wp-content\/uploads\/2018\/07\/08103843\/Jinscris-ma-voiture-%C3%A0-Zotcar.png 323w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A cette occasion, nous avons d\u00e9cid\u00e9 d\u2019offrir 100 \u20ac\u00a0 \u00e0 tous les propri\u00e9taires qui inscrivent une nouvelle voiture d\u00e8s aujourd\u2019hui. Ces 100 \u20ac vous seront revers\u00e9s 3 jours apr\u00e8s la fin de votre premi\u00e8re location. Attention : cette offre se termine le 31 mai 2018 \u00e0 12h00. Comment faire ? Pour cela, rendez-vous sur zotcar.com [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":141,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0},"categories":[42,30,25,29,24],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ZOTCAR f\u00eate ses deux ans ! - Zotcar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zotcar.com\/blog\/zotcar-fete-ses-deux-ans\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ZOTCAR f\u00eate ses deux ans ! - Zotcar\" \/>\n<meta property=\"og:description\" content=\"A cette occasion, nous avons d\u00e9cid\u00e9 d\u2019offrir 100 \u20ac\u00a0 \u00e0 tous les propri\u00e9taires qui inscrivent une nouvelle voiture d\u00e8s aujourd\u2019hui. Ces 100 \u20ac vous seront revers\u00e9s 3 jours apr\u00e8s la fin de votre premi\u00e8re location. Attention : cette offre se termine le 31 mai 2018 \u00e0 12h00. Comment faire ? Pour cela, rendez-vous sur zotcar.com [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zotcar.com\/blog\/zotcar-fete-ses-deux-ans\/\" \/>\n<meta property=\"og:site_name\" content=\"Zotcar\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/zotcar\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/zotcar\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-27T09:13:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-19T05:11:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zc-blog.s3.eu-west-1.amazonaws.com\/blog\/wp-content\/uploads\/2019\/06\/30200728\/tumblr_inline_p7ui2nBvEu1ulph39_500.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"michel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@zotcar974\" \/>\n<meta name=\"twitter:site\" content=\"@zotcar974\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"michel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.zotcar.com\/blog\/zotcar-fete-ses-deux-ans\/\",\"url\":\"https:\/\/www.zotcar.com\/blog\/zotcar-fete-ses-deux-ans\/\",\"name\":\"ZOTCAR f\u00eate ses deux ans ! - Zotcar\",\"isPartOf\":{\"@id\":\"https:\/\/www.zotcar.com\/blog\/#website\"},\"datePublished\":\"2018-04-27T09:13:58+00:00\",\"dateModified\":\"2023-07-19T05:11:34+00:00\",\"author\":{\"@id\":\"https:\/\/www.zotcar.com\/blog\/#\/schema\/person\/e605c8a3aa6efa4eb7967d86e8a6a657\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.zotcar.com\/blog\/zotcar-fete-ses-deux-ans\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.zotcar.com\/blog\/zotcar-fete-ses-deux-ans\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.zotcar.com\/blog\/zotcar-fete-ses-deux-ans\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.zotcar.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ZOTCAR f\u00eate ses deux ans !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.zotcar.com\/blog\/#website\",\"url\":\"https:\/\/www.zotcar.com\/blog\/\",\"name\":\"Zotcar\",\"description\":\"Blog de Zotcar - Location de voiture entre particuliers \u00e0 La R\u00e9union, en Martinique et en Guadeloupe\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.zotcar.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.zotcar.com\/blog\/#\/schema\/person\/e605c8a3aa6efa4eb7967d86e8a6a657\",\"name\":\"michel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.zotcar.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cfc7629b21c96d13c82cc526e7cf0ea4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cfc7629b21c96d13c82cc526e7cf0ea4?s=96&d=mm&r=g\",\"caption\":\"michel\"},\"description\":\"Michel, fondateur de Zotcar, est un entrepreneur de nature. Ses exp\u00e9riences professionnelles dans les start-up parisiennes l\u2019ont conduit \u00e0 d\u00e9velopper Zotcar, leader de la location de voiture entre particuliers \u00e0 La R\u00e9union. Passionn\u00e9 de trail, il adore parcourir les sentiers de notre belle \u00eele !\",\"sameAs\":[\"https:\/\/www.zotcar.com\",\"https:\/\/www.facebook.com\/zotcar\/\",\"https:\/\/www.instagram.com\/zotcar\/\",\"https:\/\/www.linkedin.com\/company\/10668298\",\"https:\/\/twitter.com\/zotcar974\"],\"url\":\"https:\/\/www.zotcar.com\/blog\/author\/michel\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ZOTCAR f\u00eate ses deux ans ! - Zotcar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zotcar.com\/blog\/zotcar-fete-ses-deux-ans\/","og_locale":"fr_FR","og_type":"article","og_title":"ZOTCAR f\u00eate ses deux ans ! - Zotcar","og_description":"A cette occasion, nous avons d\u00e9cid\u00e9 d\u2019offrir 100 \u20ac\u00a0 \u00e0 tous les propri\u00e9taires qui inscrivent une nouvelle voiture d\u00e8s aujourd\u2019hui. Ces 100 \u20ac vous seront revers\u00e9s 3 jours apr\u00e8s la fin de votre premi\u00e8re location. Attention : cette offre se termine le 31 mai 2018 \u00e0 12h00. Comment faire ? Pour cela, rendez-vous sur zotcar.com [&hellip;]","og_url":"https:\/\/www.zotcar.com\/blog\/zotcar-fete-ses-deux-ans\/","og_site_name":"Zotcar","article_publisher":"https:\/\/www.facebook.com\/zotcar\/","article_author":"https:\/\/www.facebook.com\/zotcar\/","article_published_time":"2018-04-27T09:13:58+00:00","article_modified_time":"2023-07-19T05:11:34+00:00","og_image":[{"width":500,"height":333,"url":"https:\/\/zc-blog.s3.eu-west-1.amazonaws.com\/blog\/wp-content\/uploads\/2019\/06\/30200728\/tumblr_inline_p7ui2nBvEu1ulph39_500.jpg","type":"image\/jpeg"}],"author":"michel","twitter_card":"summary_large_image","twitter_creator":"@zotcar974","twitter_site":"@zotcar974","twitter_misc":{"\u00c9crit par":"michel","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.zotcar.com\/blog\/zotcar-fete-ses-deux-ans\/","url":"https:\/\/www.zotcar.com\/blog\/zotcar-fete-ses-deux-ans\/","name":"ZOTCAR f\u00eate ses deux ans ! - Zotcar","isPartOf":{"@id":"https:\/\/www.zotcar.com\/blog\/#website"},"datePublished":"2018-04-27T09:13:58+00:00","dateModified":"2023-07-19T05:11:34+00:00","author":{"@id":"https:\/\/www.zotcar.com\/blog\/#\/schema\/person\/e605c8a3aa6efa4eb7967d86e8a6a657"},"breadcrumb":{"@id":"https:\/\/www.zotcar.com\/blog\/zotcar-fete-ses-deux-ans\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zotcar.com\/blog\/zotcar-fete-ses-deux-ans\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.zotcar.com\/blog\/zotcar-fete-ses-deux-ans\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.zotcar.com\/blog\/"},{"@type":"ListItem","position":2,"name":"ZOTCAR f\u00eate ses deux ans !"}]},{"@type":"WebSite","@id":"https:\/\/www.zotcar.com\/blog\/#website","url":"https:\/\/www.zotcar.com\/blog\/","name":"Zotcar","description":"Blog de Zotcar - Location de voiture entre particuliers \u00e0 La R\u00e9union, en Martinique et en Guadeloupe","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zotcar.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.zotcar.com\/blog\/#\/schema\/person\/e605c8a3aa6efa4eb7967d86e8a6a657","name":"michel","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.zotcar.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cfc7629b21c96d13c82cc526e7cf0ea4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cfc7629b21c96d13c82cc526e7cf0ea4?s=96&d=mm&r=g","caption":"michel"},"description":"Michel, fondateur de Zotcar, est un entrepreneur de nature. Ses exp\u00e9riences professionnelles dans les start-up parisiennes l\u2019ont conduit \u00e0 d\u00e9velopper Zotcar, leader de la location de voiture entre particuliers \u00e0 La R\u00e9union. Passionn\u00e9 de trail, il adore parcourir les sentiers de notre belle \u00eele !","sameAs":["https:\/\/www.zotcar.com","https:\/\/www.facebook.com\/zotcar\/","https:\/\/www.instagram.com\/zotcar\/","https:\/\/www.linkedin.com\/company\/10668298","https:\/\/twitter.com\/zotcar974"],"url":"https:\/\/www.zotcar.com\/blog\/author\/michel\/"}]}},"_links":{"self":[{"href":"https:\/\/www.zotcar.com\/blog\/wp-json\/wp\/v2\/posts\/12"}],"collection":[{"href":"https:\/\/www.zotcar.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zotcar.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zotcar.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zotcar.com\/blog\/wp-json\/wp\/v2\/comments?post=12"}],"version-history":[{"count":5,"href":"https:\/\/www.zotcar.com\/blog\/wp-json\/wp\/v2\/posts\/12\/revisions"}],"predecessor-version":[{"id":3558,"href":"https:\/\/www.zotcar.com\/blog\/wp-json\/wp\/v2\/posts\/12\/revisions\/3558"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zotcar.com\/blog\/wp-json\/wp\/v2\/media\/141"}],"wp:attachment":[{"href":"https:\/\/www.zotcar.com\/blog\/wp-json\/wp\/v2\/media?parent=12"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zotcar.com\/blog\/wp-json\/wp\/v2\/categories?post=12"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zotcar.com\/blog\/wp-json\/wp\/v2\/tags?post=12"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}